{"id":101,"date":"2022-09-06T18:50:00","date_gmt":"2022-09-06T21:50:00","guid":{"rendered":"https:\/\/blog.housi.com\/?p=101"},"modified":"2023-07-31T17:06:16","modified_gmt":"2023-07-31T20:06:16","slug":"moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade","status":"publish","type":"post","link":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/","title":{"rendered":"Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Por Desir\u00e8e Assis, g1 Bauru e Mar\u00edlia. <a href=\"https:\/\/g1.globo.com\/sp\/sao-jose-do-rio-preto-aracatuba\/mercado-imobiliario-do-interior\/noticia\/2022\/09\/06\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade.ghtml\" target=\"_blank\" rel=\"noreferrer noopener\">Publicado em 06\/09\/2022<\/a>.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Procurar um lugar para morar pode ser uma experi\u00eancia desgastante por conta da burocracia, que envolve comprova\u00e7\u00e3o de renda e garantias, ainda mais quando o processo \u00e9 feito \u00e0s pressas. Desse desafio, surge um novo modelo de loca\u00e7\u00e3o mais r\u00e1pido: a moradia por assinatura.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposta desse servi\u00e7o \u00e9 que o locat\u00e1rio escolha o im\u00f3vel reformado e equipado, sem a necessidade de um fiador ou de comprovar renda. O aluguel ainda inclui valores de condom\u00ednio, IPTU, luz, g\u00e1s e internet: tudo pago de uma \u00fanica vez.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para acessar o servi\u00e7o, basta o usu\u00e1rio escolher o im\u00f3vel que quer morar pela internet \u2013 aplicativo ou site -, determinar o per\u00edodo de estadia, que pode variar de dias at\u00e9 mais de um ano e finalizar com o pagamento.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter is-resized\"><img decoding=\"async\" src=\"https:\/\/lh6.googleusercontent.com\/XvX4bj_Fa3r0cwsk5SyPCa-HOtbWMpv9D3a861w0dSSEQaqQDxeZp5CifiY77Mw2L1h2ekznd3eomg-fQMSncahIiGMCthXUfVf45vZ0WQNZn5_5JVsRruFCNsnoiUrsknGHCnxwpHAiNNUJBS2U6hmekkosyFoQuq97rl2pRcXqLVAmHprt4kYK1Q\" alt=\"\" width=\"-57\" height=\"-31\"\/><figcaption class=\"wp-element-caption\">Moradia por assinatura garante a facilidade de cancelamento, j\u00e1 que basta um clique para que o morador decida onde quer estar \u2014 Foto: CRB Construtora\/Divulga\u00e7\u00e3o<br><\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A plataforma de moradia por assinatura garante a facilidade de cancelamento, j\u00e1 que basta um clique para que o morador decida onde quer estar. Parecido com uma plataforma de aluguel para f\u00e9rias e feriados, nesse caso, a tend\u00eancia \u00e9 acomodar o morador por um per\u00edodo mais longo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seja para o m\u00e9dico que migrou de cidade, o divorciado que precisa sair de casa, o jovem que n\u00e3o mora mais com os pais ou o trabalhador que foi transferido e precisa se acomodar: para esse p\u00fablico, o conceito de moradia por assinatura \u00e9 ideal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O presidente do Conselho Regional de Corretores de Im\u00f3veis do Estado de S\u00e3o Paulo (Creci-SP), Jos\u00e9 Augusto Viana Neto, afirmou ao <a href=\"https:\/\/g1.globo.com\/sp\/bauru-marilia\/\">G1 que<\/a> o modelo de assinatura de im\u00f3veis surge para atender a uma parcela da popula\u00e7\u00e3o mais interessada em usar e, n\u00e3o, em possuir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Concentrada em capitais, a tend\u00eancia deve, segundo o presidente, disparar para o interior de S\u00e3o Paulo, com a promessa de atrair os moradores com as facilidades de contrata\u00e7\u00e3o pela internet, flexibilidade e garantias necess\u00e1rias.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;J\u00e1 est\u00e1 acontecendo essa migra\u00e7\u00e3o. S\u00e3o Paulo possui cidades-metr\u00f3poles no interior, como <a href=\"https:\/\/g1.globo.com\/sp\/bauru-marilia\/cidade\/bauru\/\">Bauru<\/a>, <a href=\"https:\/\/g1.globo.com\/sp\/bauru-marilia\/cidade\/marilia\/\">Mar\u00edlia<\/a>, <a href=\"https:\/\/g1.globo.com\/sp\/sorocaba-jundiai\/cidade\/sorocaba\/\">Sorocaba<\/a> e <a href=\"https:\/\/g1.globo.com\/sp\/sao-jose-do-rio-preto-aracatuba\/cidade\/sao-jose-do-rio-preto\/\">S\u00e3o Jos\u00e9 do Rio Preto<\/a>, que possuem pessoas interessadas nesse tipo de moradia. S\u00e3o cidades-sede de grandes empresas que t\u00eam profissionais adeptos \u00e0 tend\u00eancia&#8221;, pontua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Conforme Augusto, essas moradias s\u00e3o melhores para aqueles que n\u00e3o possuem v\u00ednculos com a cidade em que est\u00e1 e precisa de facilidade na locomo\u00e7\u00e3o.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>No interior de SP<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/J1d_QyxlkZvjmfQ85_1gRZXbwpTBp_vEG_FZw7mnCObelMjpa3gbMgeioxOHlN46LOcpwzpFHdWsBDtbe5mlbA-h8eoY5syrk6dDSo2619g6_7yUreLzzeqlM6aCGBbgF4_ggJk7orsKgc_-ZnEd_Y0ySW_mb4_S9UuoiutbtXxPTyXsplxsZCUxkA\" alt=\"\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ao olhar para esse cen\u00e1rio, uma startup encontrou um leque de op\u00e7\u00f5es para hospedar pessoas e mudar o conceito tradicional. H\u00e1 tr\u00eas anos no mercado, a empresa \u00e9 pioneira no servi\u00e7o de moradia flex\u00edvel 100% digital, com o objetivo de reinventar a forma de morar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Em um contexto como o do Brasil, no qual uma <a href=\"https:\/\/g1.globo.com\/jornal-nacional\/noticia\/2019\/10\/04\/brasileiro-gasta-mais-de-70percent-da-renda-com-habitacao-transporte-e-comida.ghtml\">fam\u00edlia gasta em m\u00e9dia 72% da renda com habita\u00e7\u00e3o, transporte e comida<\/a>, a no\u00e7\u00e3o tradicional de moradia, enquanto patrim\u00f4nio, come\u00e7a a perder sentido.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Crescente, o movimento est\u00e1 em sintonia com os h\u00e1bitos de jovens mais interessados nos servi\u00e7os e na localiza\u00e7\u00e3o do que na posse. Segundo o empres\u00e1rio Alexandre Frankel, atual CEO da startup, 82% desse p\u00fablico preferem alugar a comprar, porcentual que supera a m\u00e9dia nacional.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter\"><img decoding=\"async\" src=\"https:\/\/lh3.googleusercontent.com\/iYYM8wY-O5_sncW0QAIpwZUKwbB1bjQXcKNizuwJBFzsSJt2AXvVep6X0broFS9sRNtgMO2D3kc5tA03UiWvVYsfnlfig7P4sYXp4fF0lqSLHuPvykWuW03X59gpNb_lN4YQjwyH-bn2kJA04ujaDzjuvQpT8jWY6OUHWzcR2eloXwrOBt3tOKi_Tg\" alt=\"\"\/><figcaption class=\"wp-element-caption\">Alexandre Frankel empres\u00e1rio e CEO da startup \u2014 Foto: Housi\/Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Ao <a href=\"https:\/\/g1.globo.com\/sp\/bauru-marilia\/\">g1<\/a>, Alexandre explicou que esse servi\u00e7o j\u00e1 existe em <a href=\"https:\/\/g1.globo.com\/sp\/campinas-regiao\/cidade\/campinas\/\">Campinas (SP)<\/a>, <a href=\"https:\/\/g1.globo.com\/sp\/ribeirao-preto-franca\/cidade\/ribeirao-preto\/\">Ribeir\u00e3o Preto (SP)<\/a>, <a href=\"https:\/\/g1.globo.com\/sp\/sao-carlos-regiao\/cidade\/sao-carlos\/\">S\u00e3o Carlos (SP)<\/a>, <a href=\"https:\/\/g1.globo.com\/sp\/sao-jose-do-rio-preto-aracatuba\/cidade\/sao-jose-do-rio-preto\/\">S\u00e3o Jos\u00e9 do Rio Preto (SP)<\/a>, <a href=\"https:\/\/g1.globo.com\/sp\/piracicaba-regiao\/cidade\/santa-barbara-doeste\/\">Santa B\u00e1rbara D&#8217;Oeste<\/a> (SP), <a href=\"https:\/\/g1.globo.com\/sp\/vale-do-paraiba-regiao\/cidade\/sao-jose-dos-campos\/\">S\u00e3o Jos\u00e9 dos Campos (SP)<\/a> e <a href=\"https:\/\/g1.globo.com\/sp\/presidente-prudente-regiao\/cidade\/presidente-prudente\/\">Presidente Prudente (SP)<\/a>. Em todas essas cidades, os empreendimentos est\u00e3o em fase de lan\u00e7amento e constru\u00e7\u00e3o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;H\u00e1 um forte crescimento desta demanda de moradia flex\u00edvel, e, em especial, por assinatura. O comportamento do usu\u00e1rio de moradia mudou e a tend\u00eancia \u00e9 que ainda em 2022 tenhamos n\u00fameros ainda mais expressivos&#8221;, explica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Leia o artigo orginal em: <a href=\"https:\/\/g1.globo.com\/sp\/sao-jose-do-rio-preto-aracatuba\/mercado-imobiliario-do-interior\/noticia\/2022\/09\/06\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade.ghtml\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/g1.globo.com\/sp\/sao-jose-do-rio-preto-aracatuba\/mercado-imobiliario-do-interior\/noticia\/2022\/09\/06\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade.ghtml<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Desir\u00e8e Assis, g1 Bauru e Mar\u00edlia. Publicado em 06\/09\/2022. Procurar um lugar para morar pode ser uma experi\u00eancia desgastante por conta da burocracia, que envolve comprova\u00e7\u00e3o de renda e garantias, ainda mais quando o processo \u00e9 feito \u00e0s pressas. Desse desafio, surge um novo modelo de loca\u00e7\u00e3o mais r\u00e1pido: a moradia por assinatura. A [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":602,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade - Blog Housi<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade - Blog Housi\" \/>\n<meta property=\"og:description\" content=\"Por Desir\u00e8e Assis, g1 Bauru e Mar\u00edlia. Publicado em 06\/09\/2022. Procurar um lugar para morar pode ser uma experi\u00eancia desgastante por conta da burocracia, que envolve comprova\u00e7\u00e3o de renda e garantias, ainda mais quando o processo \u00e9 feito \u00e0s pressas. Desse desafio, surge um novo modelo de loca\u00e7\u00e3o mais r\u00e1pido: a moradia por assinatura. A [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/\" \/>\n<meta property=\"og:site_name\" content=\"Blog Housi\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-06T21:50:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-31T20:06:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/housi.com\/blog\/wp-content\/uploads\/2023\/06\/housi-bela-cintra-foto-housi-thomaz-assessoria-6-1-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"984\" \/>\n\t<meta property=\"og:image:height\" content=\"655\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Madu Silva\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Madu Silva\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/\",\"url\":\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/\",\"name\":\"Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade - Blog Housi\",\"isPartOf\":{\"@id\":\"https:\/\/housi.com\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/housi.com\/blog\/wp-content\/uploads\/2023\/06\/housi-bela-cintra-foto-housi-thomaz-assessoria-6-1-1.webp\",\"datePublished\":\"2022-09-06T21:50:00+00:00\",\"dateModified\":\"2023-07-31T20:06:16+00:00\",\"author\":{\"@id\":\"https:\/\/housi.com\/blog\/#\/schema\/person\/a8e50eba7ae6ed57e6b2935387f44716\"},\"breadcrumb\":{\"@id\":\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#primaryimage\",\"url\":\"https:\/\/housi.com\/blog\/wp-content\/uploads\/2023\/06\/housi-bela-cintra-foto-housi-thomaz-assessoria-6-1-1.webp\",\"contentUrl\":\"https:\/\/housi.com\/blog\/wp-content\/uploads\/2023\/06\/housi-bela-cintra-foto-housi-thomaz-assessoria-6-1-1.webp\",\"width\":984,\"height\":655},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/housi.com\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/housi.com\/blog\/#website\",\"url\":\"https:\/\/housi.com\/blog\/\",\"name\":\"Blog Housi\",\"description\":\"Saiba de todas as novidades da Housi Smart Living\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/housi.com\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/housi.com\/blog\/#\/schema\/person\/a8e50eba7ae6ed57e6b2935387f44716\",\"name\":\"Madu Silva\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/housi.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/3a7cb92cc023259e91a07f165696a5d9e3045446f7740b615e9078cae9ca0022?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/3a7cb92cc023259e91a07f165696a5d9e3045446f7740b615e9078cae9ca0022?s=96&d=mm&r=g\",\"caption\":\"Madu Silva\"},\"url\":\"https:\/\/housi.com\/blog\/author\/madu-silvahousi-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade - Blog Housi","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/","og_locale":"pt_BR","og_type":"article","og_title":"Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade - Blog Housi","og_description":"Por Desir\u00e8e Assis, g1 Bauru e Mar\u00edlia. Publicado em 06\/09\/2022. Procurar um lugar para morar pode ser uma experi\u00eancia desgastante por conta da burocracia, que envolve comprova\u00e7\u00e3o de renda e garantias, ainda mais quando o processo \u00e9 feito \u00e0s pressas. Desse desafio, surge um novo modelo de loca\u00e7\u00e3o mais r\u00e1pido: a moradia por assinatura. A [&hellip;]","og_url":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/","og_site_name":"Blog Housi","article_published_time":"2022-09-06T21:50:00+00:00","article_modified_time":"2023-07-31T20:06:16+00:00","og_image":[{"width":984,"height":655,"url":"https:\/\/housi.com\/blog\/wp-content\/uploads\/2023\/06\/housi-bela-cintra-foto-housi-thomaz-assessoria-6-1-1.webp","type":"image\/webp"}],"author":"Madu Silva","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Madu Silva","Est. tempo de leitura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/","url":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/","name":"Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade - Blog Housi","isPartOf":{"@id":"https:\/\/housi.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#primaryimage"},"image":{"@id":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#primaryimage"},"thumbnailUrl":"https:\/\/housi.com\/blog\/wp-content\/uploads\/2023\/06\/housi-bela-cintra-foto-housi-thomaz-assessoria-6-1-1.webp","datePublished":"2022-09-06T21:50:00+00:00","dateModified":"2023-07-31T20:06:16+00:00","author":{"@id":"https:\/\/housi.com\/blog\/#\/schema\/person\/a8e50eba7ae6ed57e6b2935387f44716"},"breadcrumb":{"@id":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#primaryimage","url":"https:\/\/housi.com\/blog\/wp-content\/uploads\/2023\/06\/housi-bela-cintra-foto-housi-thomaz-assessoria-6-1-1.webp","contentUrl":"https:\/\/housi.com\/blog\/wp-content\/uploads\/2023\/06\/housi-bela-cintra-foto-housi-thomaz-assessoria-6-1-1.webp","width":984,"height":655},{"@type":"BreadcrumbList","@id":"https:\/\/housi.com\/blog\/noticias\/moradia-por-assinatura-tendencia-dispara-no-interior-de-sp-e-atrai-interessados-em-flexibilidade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/housi.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Moradia por assinatura: tend\u00eancia dispara no interior de SP e atrai interessados em flexibilidade"}]},{"@type":"WebSite","@id":"https:\/\/housi.com\/blog\/#website","url":"https:\/\/housi.com\/blog\/","name":"Blog Housi","description":"Saiba de todas as novidades da Housi Smart Living","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/housi.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/housi.com\/blog\/#\/schema\/person\/a8e50eba7ae6ed57e6b2935387f44716","name":"Madu Silva","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/housi.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/3a7cb92cc023259e91a07f165696a5d9e3045446f7740b615e9078cae9ca0022?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a7cb92cc023259e91a07f165696a5d9e3045446f7740b615e9078cae9ca0022?s=96&d=mm&r=g","caption":"Madu Silva"},"url":"https:\/\/housi.com\/blog\/author\/madu-silvahousi-com-br\/"}]}},"views":4552,"_links":{"self":[{"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/posts\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/comments?post=101"}],"version-history":[{"count":1,"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/posts\/101\/revisions"}],"predecessor-version":[{"id":698,"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/posts\/101\/revisions\/698"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/media\/602"}],"wp:attachment":[{"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/media?parent=101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/categories?post=101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/housi.com\/blog\/wp-json\/wp\/v2\/tags?post=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}